{"id":59900,"date":"2024-10-08T12:09:47","date_gmt":"2024-10-08T18:09:47","guid":{"rendered":"https:\/\/summainferno.com\/?p=59900"},"modified":"2024-10-08T12:09:47","modified_gmt":"2024-10-08T18:09:47","slug":"la-noche-mistica-de-wardruna-en-el-auditorio-blackberry","status":"publish","type":"post","link":"https:\/\/summainferno.com\/en\/la-noche-mistica-de-wardruna-en-el-auditorio-blackberry\/","title":{"rendered":"La noche m\u00edstica de Wardruna en el Auditorio BlackBerry"},"content":{"rendered":"<p class=\"wp-block-paragraph\">La noche del domingo 06 de octubre quedar\u00e1 marcada en el recuerdo de los amantes de las culturas n\u00f3rdicas gracias a la maravillosa presentaci\u00f3n de <strong>Wardruna<\/strong>, quienes transformaron el auditorio BlackBerry por un momento en una aldea escandinava en la que guerreros y doncellas se dieron cita para recibir todo un ritual cham\u00e1nico por parte de los noruegos. Toda una exitosa primera vez en nuestro pa\u00eds que de hecho fue <em>sold out<\/em> desde d\u00edas antes del evento. <\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1024\" height=\"682\" loading=\"lazy\" src=\"https:\/\/summainferno.com\/wp-content\/uploads\/2024\/10\/462239278_949396927228672_458011117122609546_n-1024x682.jpg\" alt=\"\" class=\"wp-image-59902\" title=\"\" srcset=\"https:\/\/summainferno.com\/wp-content\/uploads\/2024\/10\/462239278_949396927228672_458011117122609546_n-1024x682.jpg 1024w, https:\/\/summainferno.com\/wp-content\/uploads\/2024\/10\/462239278_949396927228672_458011117122609546_n-300x200.jpg 300w, https:\/\/summainferno.com\/wp-content\/uploads\/2024\/10\/462239278_949396927228672_458011117122609546_n-770x513.jpg 770w, https:\/\/summainferno.com\/wp-content\/uploads\/2024\/10\/462239278_949396927228672_458011117122609546_n-1536x1024.jpg 1536w, https:\/\/summainferno.com\/wp-content\/uploads\/2024\/10\/462239278_949396927228672_458011117122609546_n-18x12.jpg 18w, https:\/\/summainferno.com\/wp-content\/uploads\/2024\/10\/462239278_949396927228672_458011117122609546_n-360x240.jpg 360w, https:\/\/summainferno.com\/wp-content\/uploads\/2024\/10\/462239278_949396927228672_458011117122609546_n-1155x770.jpg 1155w, https:\/\/summainferno.com\/wp-content\/uploads\/2024\/10\/462239278_949396927228672_458011117122609546_n-370x247.jpg 370w, https:\/\/summainferno.com\/wp-content\/uploads\/2024\/10\/462239278_949396927228672_458011117122609546_n-293x195.jpg 293w, https:\/\/summainferno.com\/wp-content\/uploads\/2024\/10\/462239278_949396927228672_458011117122609546_n-1400x933.jpg 1400w, https:\/\/summainferno.com\/wp-content\/uploads\/2024\/10\/462239278_949396927228672_458011117122609546_n-120x80.jpg 120w, https:\/\/summainferno.com\/wp-content\/uploads\/2024\/10\/462239278_949396927228672_458011117122609546_n-240x160.jpg 240w, https:\/\/summainferno.com\/wp-content\/uploads\/2024\/10\/462239278_949396927228672_458011117122609546_n-390x260.jpg 390w, https:\/\/summainferno.com\/wp-content\/uploads\/2024\/10\/462239278_949396927228672_458011117122609546_n.jpg 2000w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><noscript><img decoding=\"async\" width=\"1024\" height=\"682\" src=\"https:\/\/summainferno.com\/wp-content\/uploads\/2024\/10\/462239278_949396927228672_458011117122609546_n-1024x682.jpg\" alt=\"\" class=\"wp-image-59902\" title=\"\" srcset=\"https:\/\/summainferno.com\/wp-content\/uploads\/2024\/10\/462239278_949396927228672_458011117122609546_n-1024x682.jpg 1024w, https:\/\/summainferno.com\/wp-content\/uploads\/2024\/10\/462239278_949396927228672_458011117122609546_n-300x200.jpg 300w, https:\/\/summainferno.com\/wp-content\/uploads\/2024\/10\/462239278_949396927228672_458011117122609546_n-770x513.jpg 770w, https:\/\/summainferno.com\/wp-content\/uploads\/2024\/10\/462239278_949396927228672_458011117122609546_n-1536x1024.jpg 1536w, https:\/\/summainferno.com\/wp-content\/uploads\/2024\/10\/462239278_949396927228672_458011117122609546_n-18x12.jpg 18w, https:\/\/summainferno.com\/wp-content\/uploads\/2024\/10\/462239278_949396927228672_458011117122609546_n-360x240.jpg 360w, https:\/\/summainferno.com\/wp-content\/uploads\/2024\/10\/462239278_949396927228672_458011117122609546_n-1155x770.jpg 1155w, https:\/\/summainferno.com\/wp-content\/uploads\/2024\/10\/462239278_949396927228672_458011117122609546_n-370x247.jpg 370w, https:\/\/summainferno.com\/wp-content\/uploads\/2024\/10\/462239278_949396927228672_458011117122609546_n-293x195.jpg 293w, https:\/\/summainferno.com\/wp-content\/uploads\/2024\/10\/462239278_949396927228672_458011117122609546_n-1400x933.jpg 1400w, https:\/\/summainferno.com\/wp-content\/uploads\/2024\/10\/462239278_949396927228672_458011117122609546_n-120x80.jpg 120w, https:\/\/summainferno.com\/wp-content\/uploads\/2024\/10\/462239278_949396927228672_458011117122609546_n-240x160.jpg 240w, https:\/\/summainferno.com\/wp-content\/uploads\/2024\/10\/462239278_949396927228672_458011117122609546_n-390x260.jpg 390w, https:\/\/summainferno.com\/wp-content\/uploads\/2024\/10\/462239278_949396927228672_458011117122609546_n.jpg 2000w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/noscript><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Pese a que Dilemma -la productora del show- anunci\u00f3 con mucha anticipaci\u00f3n que la apertura de puertas estar\u00eda disponible desde las 6:00 PM y la banda saldr\u00eda a tocar 8:30 PM, la gente tuvo a mal el querer llegar todos a casi la mera hora del show. Esto gener\u00f3 que se hiciera una fila enorme que le daba la vuelta completa a la cuadra y ocasiono que varias personas no pudieran entrar hasta que ya hab\u00edan pasado una tercia de temas. Pero quienes se anticiparon y entraron puntual pudieron disfrutar de la m\u00e1gica apertura de temas como <em>&#8220;Kvitravn<\/em>&#8220;, &#8220;<em>Skugge<\/em>&quot; and <em>&#8220;Solringen<\/em>&#8220;. La voz cavernosa de <strong>Einar Selvik<\/strong> retumbaba como si estuvi\u00e9semos dentro de una cueva oculta en alg\u00fan bosque del norte de Europa, mientras que <strong>Lindy-Fay Hella<\/strong> cantaba cual deidad m\u00edstica al mismo tiempo que danzaba como si estuviera pose\u00edda por alg\u00fan or\u00e1culo, en temas como <em>&#8220;Hertan&#8221;, &#8220;Heimta Thurs&#8221;<\/em> and <em>&#8220;Lyfjaberg&#8221;<\/em>. En &#8220;<em>Volusp\u00e1&#8221;<\/em> la banda dejar\u00eda solo a <strong>Einar<\/strong> quien interpretar\u00eda dicho tema en una forma po\u00e9tica y por dem\u00e1s hipnotizante. <\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1024\" height=\"682\" loading=\"lazy\" src=\"https:\/\/summainferno.com\/wp-content\/uploads\/2024\/10\/462362329_949396803895351_1803568726395570567_n-1024x682.jpg\" alt=\"\" class=\"wp-image-59903\" title=\"\" srcset=\"https:\/\/summainferno.com\/wp-content\/uploads\/2024\/10\/462362329_949396803895351_1803568726395570567_n-1024x682.jpg 1024w, https:\/\/summainferno.com\/wp-content\/uploads\/2024\/10\/462362329_949396803895351_1803568726395570567_n-300x200.jpg 300w, https:\/\/summainferno.com\/wp-content\/uploads\/2024\/10\/462362329_949396803895351_1803568726395570567_n-770x513.jpg 770w, https:\/\/summainferno.com\/wp-content\/uploads\/2024\/10\/462362329_949396803895351_1803568726395570567_n-1536x1024.jpg 1536w, https:\/\/summainferno.com\/wp-content\/uploads\/2024\/10\/462362329_949396803895351_1803568726395570567_n-18x12.jpg 18w, https:\/\/summainferno.com\/wp-content\/uploads\/2024\/10\/462362329_949396803895351_1803568726395570567_n-360x240.jpg 360w, https:\/\/summainferno.com\/wp-content\/uploads\/2024\/10\/462362329_949396803895351_1803568726395570567_n-1155x770.jpg 1155w, https:\/\/summainferno.com\/wp-content\/uploads\/2024\/10\/462362329_949396803895351_1803568726395570567_n-370x247.jpg 370w, https:\/\/summainferno.com\/wp-content\/uploads\/2024\/10\/462362329_949396803895351_1803568726395570567_n-293x195.jpg 293w, https:\/\/summainferno.com\/wp-content\/uploads\/2024\/10\/462362329_949396803895351_1803568726395570567_n-1400x933.jpg 1400w, https:\/\/summainferno.com\/wp-content\/uploads\/2024\/10\/462362329_949396803895351_1803568726395570567_n-120x80.jpg 120w, https:\/\/summainferno.com\/wp-content\/uploads\/2024\/10\/462362329_949396803895351_1803568726395570567_n-240x160.jpg 240w, https:\/\/summainferno.com\/wp-content\/uploads\/2024\/10\/462362329_949396803895351_1803568726395570567_n-390x260.jpg 390w, https:\/\/summainferno.com\/wp-content\/uploads\/2024\/10\/462362329_949396803895351_1803568726395570567_n.jpg 2000w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><noscript><img decoding=\"async\" width=\"1024\" height=\"682\" src=\"https:\/\/summainferno.com\/wp-content\/uploads\/2024\/10\/462362329_949396803895351_1803568726395570567_n-1024x682.jpg\" alt=\"\" class=\"wp-image-59903\" title=\"\" srcset=\"https:\/\/summainferno.com\/wp-content\/uploads\/2024\/10\/462362329_949396803895351_1803568726395570567_n-1024x682.jpg 1024w, https:\/\/summainferno.com\/wp-content\/uploads\/2024\/10\/462362329_949396803895351_1803568726395570567_n-300x200.jpg 300w, https:\/\/summainferno.com\/wp-content\/uploads\/2024\/10\/462362329_949396803895351_1803568726395570567_n-770x513.jpg 770w, https:\/\/summainferno.com\/wp-content\/uploads\/2024\/10\/462362329_949396803895351_1803568726395570567_n-1536x1024.jpg 1536w, https:\/\/summainferno.com\/wp-content\/uploads\/2024\/10\/462362329_949396803895351_1803568726395570567_n-18x12.jpg 18w, https:\/\/summainferno.com\/wp-content\/uploads\/2024\/10\/462362329_949396803895351_1803568726395570567_n-360x240.jpg 360w, https:\/\/summainferno.com\/wp-content\/uploads\/2024\/10\/462362329_949396803895351_1803568726395570567_n-1155x770.jpg 1155w, https:\/\/summainferno.com\/wp-content\/uploads\/2024\/10\/462362329_949396803895351_1803568726395570567_n-370x247.jpg 370w, https:\/\/summainferno.com\/wp-content\/uploads\/2024\/10\/462362329_949396803895351_1803568726395570567_n-293x195.jpg 293w, https:\/\/summainferno.com\/wp-content\/uploads\/2024\/10\/462362329_949396803895351_1803568726395570567_n-1400x933.jpg 1400w, https:\/\/summainferno.com\/wp-content\/uploads\/2024\/10\/462362329_949396803895351_1803568726395570567_n-120x80.jpg 120w, https:\/\/summainferno.com\/wp-content\/uploads\/2024\/10\/462362329_949396803895351_1803568726395570567_n-240x160.jpg 240w, https:\/\/summainferno.com\/wp-content\/uploads\/2024\/10\/462362329_949396803895351_1803568726395570567_n-390x260.jpg 390w, https:\/\/summainferno.com\/wp-content\/uploads\/2024\/10\/462362329_949396803895351_1803568726395570567_n.jpg 2000w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/noscript><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Fue sorprendente lo en serio y casi religioso que el p\u00fablico se tom\u00f3 el show, ya que mientras <strong>Wardruna<\/strong> tocaba el foro permanec\u00eda en un total y respetuoso silencio, callando y rega\u00f1ando incluso a quienes se les ocurr\u00eda querer decir algo en voz alta. Pero eso s\u00ed , cada que terminaba un tema y empezaba otro el auditorio explotaba en aplausos y gritos euf\u00f3ricos como lo vimos en <em>&#8220;Tyr&#8221;<\/em> , &#8220;<em>Isa<\/em>&quot; and <em>&#8220;Gr\u00e1&#8221;<\/em> . Hay que admitir que adem\u00e1s de lo musical al show de <strong>Wardruna<\/strong> le aportan mucho los juegos de luces en el escenario en medio de la oscuridad ya que simulando rel\u00e1mpagos, apag\u00e1ndose de repente en momentos cl\u00edmax o proyectando en la pared de forma gigante las sombras de los m\u00fasicos completaban una experiencia completa de viaje no solo auditivo. <em>&#8220;Runaljod&#8221;, &#8220;Rotlaust tre fell&#8221; <\/em>and<em> &#8220;Fehu&#8221;<\/em> ser\u00edan muy disfrutadas por los asistentes que hay que comentarlo eran una combinaci\u00f3n de tribus por dem\u00e1s curiosa: desde <em>black metaleros<\/em> que siguen al proyecto por el pasado de <strong>Einar<\/strong> in <strong>Gorgoroth<\/strong> y pasando por personas de ropa simple y de oficina que gustan de la cultura <em>folk<\/em>, hasta gente que s\u00ed se toma muy enserio el tema con  vestimentas vikingas, tatuajes de runas y maquillaje pagano que de verdad entraban en trance casi con los ojos en blanco en cada tema. Ser\u00eda la aplaudida &#8220;<em>Helvegen&#8221;<\/em> la que dar\u00eda fin moment\u00e1neamente a la presentaci\u00f3n. <\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1024\" height=\"682\" loading=\"lazy\" src=\"https:\/\/summainferno.com\/wp-content\/uploads\/2024\/10\/462180931_949396960562002_1871754472115239404_n-1024x682.jpg\" alt=\"\" class=\"wp-image-59904\" title=\"\" srcset=\"https:\/\/summainferno.com\/wp-content\/uploads\/2024\/10\/462180931_949396960562002_1871754472115239404_n-1024x682.jpg 1024w, https:\/\/summainferno.com\/wp-content\/uploads\/2024\/10\/462180931_949396960562002_1871754472115239404_n-300x200.jpg 300w, https:\/\/summainferno.com\/wp-content\/uploads\/2024\/10\/462180931_949396960562002_1871754472115239404_n-770x513.jpg 770w, https:\/\/summainferno.com\/wp-content\/uploads\/2024\/10\/462180931_949396960562002_1871754472115239404_n-1536x1024.jpg 1536w, https:\/\/summainferno.com\/wp-content\/uploads\/2024\/10\/462180931_949396960562002_1871754472115239404_n-18x12.jpg 18w, https:\/\/summainferno.com\/wp-content\/uploads\/2024\/10\/462180931_949396960562002_1871754472115239404_n-360x240.jpg 360w, https:\/\/summainferno.com\/wp-content\/uploads\/2024\/10\/462180931_949396960562002_1871754472115239404_n-1155x770.jpg 1155w, https:\/\/summainferno.com\/wp-content\/uploads\/2024\/10\/462180931_949396960562002_1871754472115239404_n-370x247.jpg 370w, https:\/\/summainferno.com\/wp-content\/uploads\/2024\/10\/462180931_949396960562002_1871754472115239404_n-293x195.jpg 293w, https:\/\/summainferno.com\/wp-content\/uploads\/2024\/10\/462180931_949396960562002_1871754472115239404_n-1400x933.jpg 1400w, https:\/\/summainferno.com\/wp-content\/uploads\/2024\/10\/462180931_949396960562002_1871754472115239404_n-120x80.jpg 120w, https:\/\/summainferno.com\/wp-content\/uploads\/2024\/10\/462180931_949396960562002_1871754472115239404_n-240x160.jpg 240w, https:\/\/summainferno.com\/wp-content\/uploads\/2024\/10\/462180931_949396960562002_1871754472115239404_n-390x260.jpg 390w, https:\/\/summainferno.com\/wp-content\/uploads\/2024\/10\/462180931_949396960562002_1871754472115239404_n.jpg 2000w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><noscript><img decoding=\"async\" width=\"1024\" height=\"682\" src=\"https:\/\/summainferno.com\/wp-content\/uploads\/2024\/10\/462180931_949396960562002_1871754472115239404_n-1024x682.jpg\" alt=\"\" class=\"wp-image-59904\" title=\"\" srcset=\"https:\/\/summainferno.com\/wp-content\/uploads\/2024\/10\/462180931_949396960562002_1871754472115239404_n-1024x682.jpg 1024w, https:\/\/summainferno.com\/wp-content\/uploads\/2024\/10\/462180931_949396960562002_1871754472115239404_n-300x200.jpg 300w, https:\/\/summainferno.com\/wp-content\/uploads\/2024\/10\/462180931_949396960562002_1871754472115239404_n-770x513.jpg 770w, https:\/\/summainferno.com\/wp-content\/uploads\/2024\/10\/462180931_949396960562002_1871754472115239404_n-1536x1024.jpg 1536w, https:\/\/summainferno.com\/wp-content\/uploads\/2024\/10\/462180931_949396960562002_1871754472115239404_n-18x12.jpg 18w, https:\/\/summainferno.com\/wp-content\/uploads\/2024\/10\/462180931_949396960562002_1871754472115239404_n-360x240.jpg 360w, https:\/\/summainferno.com\/wp-content\/uploads\/2024\/10\/462180931_949396960562002_1871754472115239404_n-1155x770.jpg 1155w, https:\/\/summainferno.com\/wp-content\/uploads\/2024\/10\/462180931_949396960562002_1871754472115239404_n-370x247.jpg 370w, https:\/\/summainferno.com\/wp-content\/uploads\/2024\/10\/462180931_949396960562002_1871754472115239404_n-293x195.jpg 293w, https:\/\/summainferno.com\/wp-content\/uploads\/2024\/10\/462180931_949396960562002_1871754472115239404_n-1400x933.jpg 1400w, https:\/\/summainferno.com\/wp-content\/uploads\/2024\/10\/462180931_949396960562002_1871754472115239404_n-120x80.jpg 120w, https:\/\/summainferno.com\/wp-content\/uploads\/2024\/10\/462180931_949396960562002_1871754472115239404_n-240x160.jpg 240w, https:\/\/summainferno.com\/wp-content\/uploads\/2024\/10\/462180931_949396960562002_1871754472115239404_n-390x260.jpg 390w, https:\/\/summainferno.com\/wp-content\/uploads\/2024\/10\/462180931_949396960562002_1871754472115239404_n.jpg 2000w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/noscript><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">After a brief pause<strong> Wardruna<\/strong> regresar\u00eda al escenario. En ese momento <strong>Einar <\/strong>dar\u00eda un inspirador mensaje sobre la importancia de la naturaleza y su significado en todas las culturas antiguas, as\u00ed como resaltando la importancia de que las culturas y creencias no son rivales ni tienen que ser enemigas unas de las otras. Las deidades paganas se alistaban para dejar la tierra y regresar al Valhala; y ser\u00eda con &#8220;<em>Raido<\/em>&quot; and <em>&#8220;Snake Pit Poetry&#8221;<\/em> con los temas que finalizar\u00eda esta cham\u00e1nica y m\u00edstica experiencia que nadie olvidar\u00e1.  <\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1024\" height=\"682\" loading=\"lazy\" src=\"https:\/\/summainferno.com\/wp-content\/uploads\/2024\/10\/462338649_949396867228678_1219343622962128563_n-1024x682.jpg\" alt=\"\" class=\"wp-image-59905\" title=\"\" srcset=\"https:\/\/summainferno.com\/wp-content\/uploads\/2024\/10\/462338649_949396867228678_1219343622962128563_n-1024x682.jpg 1024w, https:\/\/summainferno.com\/wp-content\/uploads\/2024\/10\/462338649_949396867228678_1219343622962128563_n-300x200.jpg 300w, https:\/\/summainferno.com\/wp-content\/uploads\/2024\/10\/462338649_949396867228678_1219343622962128563_n-770x513.jpg 770w, https:\/\/summainferno.com\/wp-content\/uploads\/2024\/10\/462338649_949396867228678_1219343622962128563_n-1536x1024.jpg 1536w, https:\/\/summainferno.com\/wp-content\/uploads\/2024\/10\/462338649_949396867228678_1219343622962128563_n-18x12.jpg 18w, https:\/\/summainferno.com\/wp-content\/uploads\/2024\/10\/462338649_949396867228678_1219343622962128563_n-360x240.jpg 360w, https:\/\/summainferno.com\/wp-content\/uploads\/2024\/10\/462338649_949396867228678_1219343622962128563_n-1155x770.jpg 1155w, https:\/\/summainferno.com\/wp-content\/uploads\/2024\/10\/462338649_949396867228678_1219343622962128563_n-370x247.jpg 370w, https:\/\/summainferno.com\/wp-content\/uploads\/2024\/10\/462338649_949396867228678_1219343622962128563_n-293x195.jpg 293w, https:\/\/summainferno.com\/wp-content\/uploads\/2024\/10\/462338649_949396867228678_1219343622962128563_n-1400x933.jpg 1400w, https:\/\/summainferno.com\/wp-content\/uploads\/2024\/10\/462338649_949396867228678_1219343622962128563_n-120x80.jpg 120w, https:\/\/summainferno.com\/wp-content\/uploads\/2024\/10\/462338649_949396867228678_1219343622962128563_n-240x160.jpg 240w, https:\/\/summainferno.com\/wp-content\/uploads\/2024\/10\/462338649_949396867228678_1219343622962128563_n-390x260.jpg 390w, https:\/\/summainferno.com\/wp-content\/uploads\/2024\/10\/462338649_949396867228678_1219343622962128563_n.jpg 2000w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><noscript><img decoding=\"async\" width=\"1024\" height=\"682\" src=\"https:\/\/summainferno.com\/wp-content\/uploads\/2024\/10\/462338649_949396867228678_1219343622962128563_n-1024x682.jpg\" alt=\"\" class=\"wp-image-59905\" title=\"\" srcset=\"https:\/\/summainferno.com\/wp-content\/uploads\/2024\/10\/462338649_949396867228678_1219343622962128563_n-1024x682.jpg 1024w, https:\/\/summainferno.com\/wp-content\/uploads\/2024\/10\/462338649_949396867228678_1219343622962128563_n-300x200.jpg 300w, https:\/\/summainferno.com\/wp-content\/uploads\/2024\/10\/462338649_949396867228678_1219343622962128563_n-770x513.jpg 770w, https:\/\/summainferno.com\/wp-content\/uploads\/2024\/10\/462338649_949396867228678_1219343622962128563_n-1536x1024.jpg 1536w, https:\/\/summainferno.com\/wp-content\/uploads\/2024\/10\/462338649_949396867228678_1219343622962128563_n-18x12.jpg 18w, https:\/\/summainferno.com\/wp-content\/uploads\/2024\/10\/462338649_949396867228678_1219343622962128563_n-360x240.jpg 360w, https:\/\/summainferno.com\/wp-content\/uploads\/2024\/10\/462338649_949396867228678_1219343622962128563_n-1155x770.jpg 1155w, https:\/\/summainferno.com\/wp-content\/uploads\/2024\/10\/462338649_949396867228678_1219343622962128563_n-370x247.jpg 370w, https:\/\/summainferno.com\/wp-content\/uploads\/2024\/10\/462338649_949396867228678_1219343622962128563_n-293x195.jpg 293w, https:\/\/summainferno.com\/wp-content\/uploads\/2024\/10\/462338649_949396867228678_1219343622962128563_n-1400x933.jpg 1400w, https:\/\/summainferno.com\/wp-content\/uploads\/2024\/10\/462338649_949396867228678_1219343622962128563_n-120x80.jpg 120w, https:\/\/summainferno.com\/wp-content\/uploads\/2024\/10\/462338649_949396867228678_1219343622962128563_n-240x160.jpg 240w, https:\/\/summainferno.com\/wp-content\/uploads\/2024\/10\/462338649_949396867228678_1219343622962128563_n-390x260.jpg 390w, https:\/\/summainferno.com\/wp-content\/uploads\/2024\/10\/462338649_949396867228678_1219343622962128563_n.jpg 2000w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/noscript><\/figure>","protected":false},"excerpt":{"rendered":"<p>La noche del domingo 06 de octubre quedar\u00e1 marcada en el recuerdo de los amantes de las culturas n\u00f3rdicas gracias a la maravillosa presentaci\u00f3n de Wardruna, quienes transformaron el auditorio BlackBerry por un momento en una aldea escandinava en la que guerreros y doncellas se dieron cita para recibir todo un ritual cham\u00e1nico por parte de los noruegos. Toda una exitosa primera vez en nuestro pa\u00eds que de hecho fue sold out desde d\u00edas antes del evento. Pese a que [&hellip;]<\/p>\n","protected":false},"author":9,"featured_media":59901,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[188],"tags":[4398],"class_list":["post-59900","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-show-review","tag-wardruna"],"_links":{"self":[{"href":"https:\/\/summainferno.com\/en\/wp-json\/wp\/v2\/posts\/59900","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/summainferno.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/summainferno.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/summainferno.com\/en\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/summainferno.com\/en\/wp-json\/wp\/v2\/comments?post=59900"}],"version-history":[{"count":2,"href":"https:\/\/summainferno.com\/en\/wp-json\/wp\/v2\/posts\/59900\/revisions"}],"predecessor-version":[{"id":59907,"href":"https:\/\/summainferno.com\/en\/wp-json\/wp\/v2\/posts\/59900\/revisions\/59907"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/summainferno.com\/en\/wp-json\/wp\/v2\/media\/59901"}],"wp:attachment":[{"href":"https:\/\/summainferno.com\/en\/wp-json\/wp\/v2\/media?parent=59900"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/summainferno.com\/en\/wp-json\/wp\/v2\/categories?post=59900"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/summainferno.com\/en\/wp-json\/wp\/v2\/tags?post=59900"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}