{"id":5567,"date":"2014-08-22T10:44:17","date_gmt":"2014-08-22T15:44:17","guid":{"rendered":"http:\/\/summainferno.com\/?post_type=it_conciertos&amp;p=5567"},"modified":"2014-08-22T10:44:17","modified_gmt":"2014-08-22T15:44:17","slug":"zakk-wylde-y-su-black-label-society-deleitaron-en-el-jose-cuervo-salon","status":"publish","type":"post","link":"https:\/\/summainferno.com\/en\/zakk-wylde-y-su-black-label-society-deleitaron-en-el-jose-cuervo-salon\/","title":{"rendered":"Zakk Wylde y su BLACK LABEL SOCIETY deleitaron en el Jos\u00e9 Cuervo Sal\u00f3n."},"content":{"rendered":"<hr \/>\n<p><em>&#8220;Maldita lluvia. Me har\u00e1 llegar tarde.&#8221;<\/em> me dec\u00eda mientras me dirig\u00eda al<strong> Jos\u00e9 Cuervo Sal\u00f3n<\/strong> para asistir al regreso de <strong>Black Label Society<\/strong> y por consiguiente de su legendario lider, <strong>Zakk Wylde<\/strong> a nuestro pa\u00eds, esta vez presentando su nueva producci\u00f3n <em>&#8216;Catacombs of the Black Vatican.&#8221;\u00a0<\/em><\/p>\n<p>La marea de playeras negras con el logo de la banda llenaron el recinto de Polanco en esta noche borrascosa; todos esperando ver sobre el escenario a <strong>Wylde<\/strong> mostrando todo su virtuosismo con la guitarra.<\/p>\n<p>La noche comenz\u00f3 con la presentaci\u00f3n de <strong>Battlecross<\/strong>, banda originaria de Michigan y que apenas el a\u00f1o pasado lanzaron su tercera producci\u00f3n, <em>&#8216;War of Will&#8217;<\/em>. Y a decir verdad realmente lo hicieron muy bien, conectaron con el p\u00fablico, haciendo que incluso coreare el nombre de la banda a la mitad de su presentaci\u00f3n. Son r\u00e1pidos, son agresivos, son muy buenos y seguramente con el tiempo y una carrera m\u00e1s asentada, volver\u00e1n a liderar un show completo. Gran banda telonera, con un futuro alentador.<\/p>\n<p>Tras la presentaci\u00f3n de <strong>Battlecross<\/strong>, frente al escenario apareci\u00f3 una enorme manta que lo cubr\u00eda por completo. El p\u00fablico, expectante y emocionado. Casi en punto de las diez de la noche, una lluvia de luces rojas anunciaron la llegada de <strong>Zakk Wylde<\/strong> y compa\u00f1ia, quienes iniciaron como ya es costumbre con <em>&#8216;The Beginnig&#8230; at Last&#8217;<\/em>. <strong>Wylde<\/strong> se vi\u00f3 en\u00e9rgico, poderoso sobre el escenario mientras ejecutaba con maestr\u00eda y canciones como<em> &#8216;Funeral Bell&#8217;, &#8216;Suicide Messiah&#8217;, &#8216;In this River&#8217; y &#8216; Damn the Flood&#8217;<\/em> volaban por los aires.<\/p>\n<p>Los asistentes estaban totalmente en \u00e9xtasis, eso es seguro. Ayud\u00f3 a esto, el gran empe\u00f1o en la calidad del audio que la producci\u00f3n del evento provey\u00f3 para el show. Adem\u00e1s de los grandes cl\u00e1sicos de la banda, no pod\u00edan faltar los temas de su nuevo \u00e1lbum, por lo que hicieron aparici\u00f3n canciones como <em>&#8216;Angel of Mercy&#8217;<\/em> o el primer single de la producci\u00f3n, <em>&#8216;My Dying Time&#8217;<\/em>.<\/p>\n<p>La noche termin\u00f3 con <em>&#8216;Stillborn&#8217;<\/em>, dejando tras de si, 13 canciones interpretadas, un solo de guitarra digno de los m\u00e1s grandes exponentes a nivel mundial y un muy conmovedor homenaje a <strong>Dimmebag Darrel<\/strong>, quien esa noche cumplir\u00eda 48 a\u00f1os de seguir vivo. <strong>Black Label Society<\/strong> regres\u00f3 a nuestro pa\u00eds y seguramente volver\u00e1 de nuevo en un futuro, pero esta noche ser\u00e1 dif\u00edcil de superar. Se los dejo como reto.<\/p>","protected":false},"excerpt":{"rendered":"<p>&#8220;Maldita lluvia. Me har\u00e1 llegar tarde.&#8221; me dec\u00eda mientras me dirig\u00eda al Jos\u00e9 Cuervo Sal\u00f3n para asistir al regreso de Black Label Society y por consiguiente de su legendario lider, Zakk Wylde a nuestro pa\u00eds, esta vez presentando su nueva producci\u00f3n &#8216;Catacombs of the Black Vatican.&#8221;\u00a0 La marea de playeras negras con el logo de la banda llenaron el recinto de Polanco en esta noche borrascosa; todos esperando ver sobre el escenario a Wylde mostrando todo su virtuosismo con la [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":5568,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[171,188],"tags":[],"class_list":["post-5567","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-heavy-metal","category-show-review"],"_links":{"self":[{"href":"https:\/\/summainferno.com\/en\/wp-json\/wp\/v2\/posts\/5567","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/summainferno.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/summainferno.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/summainferno.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/summainferno.com\/en\/wp-json\/wp\/v2\/comments?post=5567"}],"version-history":[{"count":0,"href":"https:\/\/summainferno.com\/en\/wp-json\/wp\/v2\/posts\/5567\/revisions"}],"wp:attachment":[{"href":"https:\/\/summainferno.com\/en\/wp-json\/wp\/v2\/media?parent=5567"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/summainferno.com\/en\/wp-json\/wp\/v2\/categories?post=5567"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/summainferno.com\/en\/wp-json\/wp\/v2\/tags?post=5567"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}