{"id":37070,"date":"2020-07-08T16:34:03","date_gmt":"2020-07-08T22:34:03","guid":{"rendered":"https:\/\/summainferno.com\/?p=37070"},"modified":"2020-07-08T20:35:57","modified_gmt":"2020-07-09T02:35:57","slug":"saints-of-death-ascend-to-the-throne","status":"publish","type":"post","link":"https:\/\/summainferno.com\/en\/saints-of-death-ascend-to-the-throne\/","title":{"rendered":"Saints Of Death - &#039;Ascend To The Throne&#039;"},"content":{"rendered":"<div class=\"lets-review-block__wrap lets-review-block__wrap-10 lr-cf lets-review-wrap-37070 lets-review--left lets-review-skin-2 lets-review-design-6 lets-review-ani-3 lets-review-score-type-4 lets-review-type-2 lets-review-score-type__icon lets-review--side conclusion__off proscons__off\" data-design=\"6\" data-score-type=\"4\" data-skin=\"2\"><div class=\"lets-review-block lets-review-block__img\"\"><img decoding=\"async\" loading=\"lazy\" width=\"1488\" height=\"1488\" src=\"https:\/\/summainferno.com\/wp-content\/uploads\/2020\/07\/336485.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/summainferno.com\/wp-content\/uploads\/2020\/07\/336485.jpg 1488w, https:\/\/summainferno.com\/wp-content\/uploads\/2020\/07\/336485-300x300.jpg 300w, https:\/\/summainferno.com\/wp-content\/uploads\/2020\/07\/336485-1024x1024.jpg 1024w, https:\/\/summainferno.com\/wp-content\/uploads\/2020\/07\/336485-150x150.jpg 150w, https:\/\/summainferno.com\/wp-content\/uploads\/2020\/07\/336485-768x768.jpg 768w, https:\/\/summainferno.com\/wp-content\/uploads\/2020\/07\/336485-24x24.jpg 24w, https:\/\/summainferno.com\/wp-content\/uploads\/2020\/07\/336485-48x48.jpg 48w, https:\/\/summainferno.com\/wp-content\/uploads\/2020\/07\/336485-96x96.jpg 96w\" sizes=\"auto, (max-width: 1488px) 100vw, 1488px\" title=\"\"><noscript><img decoding=\"async\" width=\"1488\" height=\"1488\" src=\"https:\/\/summainferno.com\/wp-content\/uploads\/2020\/07\/336485.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/summainferno.com\/wp-content\/uploads\/2020\/07\/336485.jpg 1488w, https:\/\/summainferno.com\/wp-content\/uploads\/2020\/07\/336485-300x300.jpg 300w, https:\/\/summainferno.com\/wp-content\/uploads\/2020\/07\/336485-1024x1024.jpg 1024w, https:\/\/summainferno.com\/wp-content\/uploads\/2020\/07\/336485-150x150.jpg 150w, https:\/\/summainferno.com\/wp-content\/uploads\/2020\/07\/336485-768x768.jpg 768w, https:\/\/summainferno.com\/wp-content\/uploads\/2020\/07\/336485-24x24.jpg 24w, https:\/\/summainferno.com\/wp-content\/uploads\/2020\/07\/336485-48x48.jpg 48w, https:\/\/summainferno.com\/wp-content\/uploads\/2020\/07\/336485-96x96.jpg 96w\" sizes=\"(max-width: 1488px) 100vw, 1488px\" title=\"\"><\/noscript><\/div><div class=\"lets-review-block lets-review-block__final-score lets-review-block__final-score-type-4 lets-review-block__pad score-level-9\"><div class=\"score__wrap lr-all-c\" style=\"background:#ac9449; color: #fff\"><div class=\"score-overlay-wrap score-overlay-wrap__icon\"><i class=\"fas fa-fire\"><\/i><i class=\"fas fa-fire\"><\/i><i class=\"fas fa-fire\"><\/i><i class=\"fas fa-fire\"><\/i><i class=\"fas fa-fire\"><\/i><div class=\"score-overlay\" style=\"width:10%\"><\/div><\/div><div class=\"score\">4.5<\/div><\/div><\/div><\/div>\n<p class=\"wp-block-paragraph\">Dentro del metal canadiense emergente encontramos a <strong>Saints Of Death<\/strong>. Nacidos en un principio como una banda tributo a <strong>Mot\u00f6rhead<\/strong> y con la inspiraci\u00f3n del culto mexicano a la Santa Muerte para el nombre de su proyecto, cuentan con la peculiaridad de tocar con dos bajos adem\u00e1s de la imponente figura de su vocalista de m\u00e1s de dos metros de estatura <strong>Twan Holliday<\/strong>; quien adem\u00e1s ha participado como actor en pel\u00edculas de terror y tambi\u00e9n ha sido luchador profesional. <strong>Saints Of Death<\/strong> lanza este pr\u00f3ximo 10 de julio su nuevo trabajo &#8220;<em>Ascend To The Throne<\/em>&#8220;, v\u00eda <strong>Head Rattle Productions<\/strong>. Aqu\u00ed te contamos que tal est\u00e1. <\/p>\n\n\n\n<div style=\"height:29px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"800\" height=\"533\" loading=\"lazy\" src=\"https:\/\/summainferno.com\/wp-content\/uploads\/2020\/07\/454020.jpg\" alt=\"\" class=\"wp-image-37071\" title=\"\" srcset=\"https:\/\/summainferno.com\/wp-content\/uploads\/2020\/07\/454020.jpg 800w, https:\/\/summainferno.com\/wp-content\/uploads\/2020\/07\/454020-300x200.jpg 300w, https:\/\/summainferno.com\/wp-content\/uploads\/2020\/07\/454020-768x512.jpg 768w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><noscript><img decoding=\"async\" width=\"800\" height=\"533\" src=\"https:\/\/summainferno.com\/wp-content\/uploads\/2020\/07\/454020.jpg\" alt=\"\" class=\"wp-image-37071\" title=\"\" srcset=\"https:\/\/summainferno.com\/wp-content\/uploads\/2020\/07\/454020.jpg 800w, https:\/\/summainferno.com\/wp-content\/uploads\/2020\/07\/454020-300x200.jpg 300w, https:\/\/summainferno.com\/wp-content\/uploads\/2020\/07\/454020-768x512.jpg 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/noscript><\/figure>\n\n\n\n<div style=\"height:29px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">El disco contiene solo siete temas incluida la entrada &#8220;<em>Call To The Kings<\/em>&#8220;, que por supuesto deja ver de inmediato el gusto de la banda por la parafernalia de lo misterioso y terror\u00edfico. A continuaci\u00f3n nos encontramos con el tema hom\u00f3nimo del disco, que tras un inicio lento deja ir de lleno un poderoso sonido de mezcla de <em>Death Metal <\/em>mel\u00f3dico con <em>hardcore<\/em> y hasta un poco de <em>Thrash<\/em>: si te gustan proyectos como <strong>Devildriver<\/strong> este tema debes tenerlo en tu reproductor. Con la misma potencia encontramos <strong>&#8220;Watching Me Die&#8221;<\/strong>, toda una invitaci\u00f3n al slam. Llega ahora &#8220;<em>God Can\u00b4t Help You<\/em>&#8221; que es una canci\u00f3n que se inclina a bajar un poco la velocidad para obtener un sonido m\u00e1s rocoso y cercano a bandas como <strong>Pantera<\/strong>; aunque de nuevo la segunda parte de la canci\u00f3n no se puede resistir a pisar el pedal con un vertiginoso solo de guitarra. Cuando uno piensa el disco va a tener una linea marcada resulta que  &#8220;<em>Repentance<\/em>&#8221; nos sorprende con un sonido absolutamente ligado al <em>Black Metal<\/em> que demuestra que <strong>Saints Of Death<\/strong> no es una banda encasillada a seguir una sola linea en particular. &#8220;<em>You Can\u00b4t Run<\/em>&#8221; es un tema veloz y agresivo, quiz\u00e1 el que m\u00e1s <em>Thrash <\/em>suena de todo el \u00e1lbum. Hay que destacar que para esta pieza, la banda decidi\u00f3 lanzar un videoclip donde documenta su visita a nuestro pa\u00eds y plasma fragmentos de su presentaci\u00f3n gratuita en el <strong>Tianguis Cultural del Chopo<\/strong> as\u00ed como en el <strong>Sal\u00f3n Bol\u00edvar<\/strong> de la Ciudad de M\u00e9xico, en el marco de la gira &#8220;Canadian Invasion&#8221; del a\u00f1o 2018. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El disco cierra con &#8220;<em>Soldiers Of Metal<\/em>&#8220;, un tema de casi seis minutos de duraci\u00f3n que en ese tiempo entrega una brutal mezcla de sonidos desde el <em>Groove,<\/em> el <em>Stoner<\/em> y el <em>Harcdore Metal<\/em>; que sin embargo considero que es un poco repetitiva en su estructura para la extensi\u00f3n que quisieron darle: podr\u00edamos quedarnos con tres minutos del tema y hubiera estado mucho mejor y m\u00e1s pr\u00e1ctico. En resumen podemos decir que tenemos en <strong>Saints Of Death<\/strong> una propuesta muy buena y de alto voltaje que sabe mezclar lo mejor de varios estilos de metal para generar poderosos temas, y en este trabajo deja plasmado que musicalmente tienen con qu\u00e9 ganarse poco a poco un lugar en la escena del metal mundial. <\/p>\n\n\n\n<div style=\"height:42px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1024\" height=\"1024\" loading=\"lazy\" src=\"https:\/\/summainferno.com\/wp-content\/uploads\/2020\/07\/336485-1024x1024.jpg\" alt=\"\" class=\"wp-image-37072\" title=\"\" srcset=\"https:\/\/summainferno.com\/wp-content\/uploads\/2020\/07\/336485-1024x1024.jpg 1024w, https:\/\/summainferno.com\/wp-content\/uploads\/2020\/07\/336485-300x300.jpg 300w, https:\/\/summainferno.com\/wp-content\/uploads\/2020\/07\/336485-150x150.jpg 150w, https:\/\/summainferno.com\/wp-content\/uploads\/2020\/07\/336485-768x768.jpg 768w, https:\/\/summainferno.com\/wp-content\/uploads\/2020\/07\/336485-24x24.jpg 24w, https:\/\/summainferno.com\/wp-content\/uploads\/2020\/07\/336485-48x48.jpg 48w, https:\/\/summainferno.com\/wp-content\/uploads\/2020\/07\/336485-96x96.jpg 96w, https:\/\/summainferno.com\/wp-content\/uploads\/2020\/07\/336485.jpg 1488w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><noscript><img decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/summainferno.com\/wp-content\/uploads\/2020\/07\/336485-1024x1024.jpg\" alt=\"\" class=\"wp-image-37072\" title=\"\" srcset=\"https:\/\/summainferno.com\/wp-content\/uploads\/2020\/07\/336485-1024x1024.jpg 1024w, https:\/\/summainferno.com\/wp-content\/uploads\/2020\/07\/336485-300x300.jpg 300w, https:\/\/summainferno.com\/wp-content\/uploads\/2020\/07\/336485-150x150.jpg 150w, https:\/\/summainferno.com\/wp-content\/uploads\/2020\/07\/336485-768x768.jpg 768w, https:\/\/summainferno.com\/wp-content\/uploads\/2020\/07\/336485-24x24.jpg 24w, https:\/\/summainferno.com\/wp-content\/uploads\/2020\/07\/336485-48x48.jpg 48w, https:\/\/summainferno.com\/wp-content\/uploads\/2020\/07\/336485-96x96.jpg 96w, https:\/\/summainferno.com\/wp-content\/uploads\/2020\/07\/336485.jpg 1488w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/noscript><\/figure>\n<div class=\"lets-review-block__wrap lets-review-block__wrap-10 lr-cf lets-review-wrap-37070 lets-review--center lets-review-skin-2 lets-review-design-6 lets-review-ani-3 lets-review-score-type-4 lets-review-type-2 lets-review-score-type__icon proscons__off\" data-design=\"6\" data-score-type=\"4\" data-skin=\"2\"><div class=\"lets-review-block lets-review-block__img\"\"><img decoding=\"async\" loading=\"lazy\" width=\"1488\" height=\"1488\" src=\"https:\/\/summainferno.com\/wp-content\/uploads\/2020\/07\/336485.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/summainferno.com\/wp-content\/uploads\/2020\/07\/336485.jpg 1488w, https:\/\/summainferno.com\/wp-content\/uploads\/2020\/07\/336485-300x300.jpg 300w, https:\/\/summainferno.com\/wp-content\/uploads\/2020\/07\/336485-1024x1024.jpg 1024w, https:\/\/summainferno.com\/wp-content\/uploads\/2020\/07\/336485-150x150.jpg 150w, https:\/\/summainferno.com\/wp-content\/uploads\/2020\/07\/336485-768x768.jpg 768w, https:\/\/summainferno.com\/wp-content\/uploads\/2020\/07\/336485-24x24.jpg 24w, https:\/\/summainferno.com\/wp-content\/uploads\/2020\/07\/336485-48x48.jpg 48w, https:\/\/summainferno.com\/wp-content\/uploads\/2020\/07\/336485-96x96.jpg 96w\" sizes=\"auto, (max-width: 1488px) 100vw, 1488px\" title=\"\"><noscript><img decoding=\"async\" width=\"1488\" height=\"1488\" src=\"https:\/\/summainferno.com\/wp-content\/uploads\/2020\/07\/336485.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/summainferno.com\/wp-content\/uploads\/2020\/07\/336485.jpg 1488w, https:\/\/summainferno.com\/wp-content\/uploads\/2020\/07\/336485-300x300.jpg 300w, https:\/\/summainferno.com\/wp-content\/uploads\/2020\/07\/336485-1024x1024.jpg 1024w, https:\/\/summainferno.com\/wp-content\/uploads\/2020\/07\/336485-150x150.jpg 150w, https:\/\/summainferno.com\/wp-content\/uploads\/2020\/07\/336485-768x768.jpg 768w, https:\/\/summainferno.com\/wp-content\/uploads\/2020\/07\/336485-24x24.jpg 24w, https:\/\/summainferno.com\/wp-content\/uploads\/2020\/07\/336485-48x48.jpg 48w, https:\/\/summainferno.com\/wp-content\/uploads\/2020\/07\/336485-96x96.jpg 96w\" sizes=\"(max-width: 1488px) 100vw, 1488px\" title=\"\"><\/noscript><\/div><div class=\"lets-review-block lets-review-block__main-title lr-vc lets-review-block__pad\"><div class=\"lets-review-block__title lr-font-h\" style=\"\">Saints Of Death &#8211; &#8216;Ascend To The Throne&#8217;<\/div><\/div><div class=\"lets-review-block lets-review-block__conclusion__wrap lets-review-block__pad\"><div class=\"lets-review-block__conclusion__title lets-review-block__title lr-font-h\" style=\"\">Gran propuesta canadiense de metal <\/div><div class=\"lets-review-block__conclusion\">Saints Of Death entrega en esta nueva producci\u00f3n evidencia suficiente para demostrar que son una banda de un sonido por dem\u00e1s agresivo y fuerte, listo para conquistar los o\u00eddos de la escena metalera mundial. <\/div><\/div><div class=\"lets-review-block lets-review-block__final-score lets-review-block__final-score-type-4 lets-review-block__pad score-level-9\"><div class=\"score__wrap lr-all-c\" style=\"background:#ac9449; color: #fff\"><div class=\"score-overlay-wrap score-overlay-wrap__icon\"><i class=\"fas fa-fire\"><\/i><i class=\"fas fa-fire\"><\/i><i class=\"fas fa-fire\"><\/i><i class=\"fas fa-fire\"><\/i><i class=\"fas fa-fire\"><\/i><div class=\"score-overlay\" style=\"width:10%\"><\/div><\/div><div class=\"score\">4.5<\/div><\/div><\/div><\/div><script type=\"application\/ld+json\">{\"@context\": \"http:\/\/schema.org\/\",\n\t\t\t\"@type\": \"Organization\",\n\t\t\t\"name\": \"Saints Of Death &#8211; &#8216;Ascend To The Throne&#8217;\",\"image\": [\n\t\t\t\t\"https:\/\/summainferno.com\/wp-content\/uploads\/2020\/07\/336485.jpg\"\n\t\t\t],\"review\": {\n\t\t\t\t\"@type\": \"Review\",\n\t\t\t\t\"reviewRating\": {\n\t\t\t\t\t\"@type\": \"Rating\",\n\t\t\t\t\t\"worstRating\": \"0\",\n\t\t\t\t\t\"ratingValue\": \"4.5\",\n\t\t\t\t\t\"bestRating\": \"5\"\n\t\t\t\t},\n\t\t\t\t\"author\": {\n\t\t\t\t\t\"@type\": \"Person\",\n\t\t\t\t\t\"name\": \"Antonio Arizti\"\n\t\t\t\t}\n\t\t\t}}<\/script>","protected":false},"excerpt":{"rendered":"<p>Saints Of Death &#8211; &#8216;Ascend To The Throne&#8217; Gran propuesta canadiense de metal Saints Of Death entrega en esta nueva producci\u00f3n evidencia suficiente para demostrar que son una banda de un sonido por dem\u00e1s agresivo y fuerte, listo para conquistar los o\u00eddos de la escena metalera mundial. 4.5<\/p>","protected":false},"author":9,"featured_media":37072,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[225,1392,991,620],"tags":[3244],"class_list":["post-37070","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-album-reviews","category-hardcore","category-melodic-death-metal","category-thrash-metal","tag-saints-of-death"],"_links":{"self":[{"href":"https:\/\/summainferno.com\/en\/wp-json\/wp\/v2\/posts\/37070","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/summainferno.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/summainferno.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/summainferno.com\/en\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/summainferno.com\/en\/wp-json\/wp\/v2\/comments?post=37070"}],"version-history":[{"count":0,"href":"https:\/\/summainferno.com\/en\/wp-json\/wp\/v2\/posts\/37070\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/summainferno.com\/en\/wp-json\/wp\/v2\/media\/37072"}],"wp:attachment":[{"href":"https:\/\/summainferno.com\/en\/wp-json\/wp\/v2\/media?parent=37070"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/summainferno.com\/en\/wp-json\/wp\/v2\/categories?post=37070"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/summainferno.com\/en\/wp-json\/wp\/v2\/tags?post=37070"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}