{"id":21834,"date":"2018-11-15T16:47:05","date_gmt":"2018-11-15T22:47:05","guid":{"rendered":"http:\/\/summainferno.com\/?p=21834"},"modified":"2018-11-15T16:47:05","modified_gmt":"2018-11-15T22:47:05","slug":"crisix-against-the-odds","status":"publish","type":"post","link":"https:\/\/summainferno.com\/en\/crisix-against-the-odds\/","title":{"rendered":"Crisix &#8211; Against the Odds"},"content":{"rendered":"<div class=\"lets-review-block__wrap lets-review-block__wrap-10 lr-cf lets-review-wrap-21834 lets-review--left lets-review-skin-1 lets-review-design-3 lets-review-ani-1 lets-review-score-type-1 lets-review-type-2 lets-review-score-type__bar lets-review--side conclusion__off proscons__off\" data-design=\"3\" data-score-type=\"1\" data-skin=\"1\"><div class=\"lets-review-block lets-review-block__bg\"><\/div><div class=\"lets-review-block lets-review-block__final-score lets-review-block__final-score-type-1 lets-review-block__pad score-level-1\"><div class=\"score__wrap lr-all-c\" style=\"border-color:#ac9449; color: #fff\"><div class=\"score\">9<\/div><\/div><\/div><\/div><p><strong>Crisix<\/strong> es una de las bandas que m\u00e1s fuerte ha pegado en la nueva ola del <em>thrash<\/em>, con un estilo fuerte y agresivo que ha dejado boquiabierta a la prensa especializada y les ha ganado un gran acumulo de elogios y por supuesto muchos fans. Los originarios de Barcelona han tenido una historia de ensue\u00f1o ganando torneo tras torneo donde se presentan, incluyendo la prestigiosa batalla del <strong>Wacken<\/strong> en 2009. Con 3 discos previos que solo han ido superando uno tras otro el \u00e9xito de su predecesor, este 2018 nos trae<strong> &#8220;Against the Odds&#8221;<\/strong> , su cuarto material discogr\u00e1fico.<\/p>\n<p><img decoding=\"async\" loading=\"lazy\" class=\"aligncenter size-full wp-image-21835\" src=\"http:\/\/summainferno.com\/wp-content\/uploads\/2018\/11\/crisic.jpg\" alt=\"\" width=\"620\" height=\"350\" title=\"\"><noscript><img decoding=\"async\" class=\"aligncenter size-full wp-image-21835\" src=\"http:\/\/summainferno.com\/wp-content\/uploads\/2018\/11\/crisic.jpg\" alt=\"\" width=\"620\" height=\"350\" title=\"\"><\/noscript><\/p>\n<p>El disco abre con <em>&#8220;Get out of my head&#8221;<\/em> y de inmediato disipa cualquier duda sobre si la banda se ha suavizado o ha buscado experimentar de m\u00e1s en esta producci\u00f3n. Tiene el sonido caracter\u00edstico de esta nueva ola del<em> thrash<\/em>: irreverente y veloz. Un track con el que desde el principio puedes verte a ti mismo corriendo alrededor del<i>\u00a0circle pit<\/i> mientras tarareas el pegajoso coro. <em>&#8220;Leech Breeder&#8221;<\/em> sin embargo cambia un poco la atm\u00f3sfera con una inyecci\u00f3n mas gutural y potente, que vira ese sonido juvenil y de facha en uno m\u00e1s poderoso y lleno de energ\u00eda. Llegamos a <em>&#8220;Technophiliac&#8221;<\/em>que juega un poco m\u00e1s con los sube y baja durante toda la canci\u00f3n, con los constantes silenciamientos de algunos instrumentos mientras la voz de <strong>Juli Baz\u00a0<\/strong>adquiere protagonismo; para luego atascarnos de un ritmo tipo ametralladora con el coro. &#8220;<em>Perseverance<\/em>&#8221; es el cuarto tema del \u00e1lbum y sin duda tambi\u00e9n hasta el momento el que m\u00e1s coquetea con el <em>hardcore<\/em>. Hay que destacar que llevamos cuatro temas y todos son poderosos y de inmediato se enganchan a tu adrenalina, pero tambi\u00e9n que todos aunque mantienen claro la base <em>thrash<\/em>, son deliciosamente diferentes entre si: no hay lugar para la monoton\u00eda.<\/p>\n<p><em><img decoding=\"async\" loading=\"lazy\" class=\"wp-image-21836 alignright\" src=\"http:\/\/summainferno.com\/wp-content\/uploads\/2018\/11\/CRISIX-2.jpg\" alt=\"\" width=\"409\" height=\"614\" title=\"\"><noscript><img decoding=\"async\" class=\"wp-image-21836 alignright\" src=\"http:\/\/summainferno.com\/wp-content\/uploads\/2018\/11\/CRISIX-2.jpg\" alt=\"\" width=\"409\" height=\"614\" title=\"\"><\/noscript>&#8220;Xenomorph Blood&#8221;,<\/em>\u00a0tema inspirado en la saga de pel\u00edculas de <strong>Alien: el octavo pasajero<\/strong> sin embargo, es un peque\u00f1o bache a lo majestuoso que ven\u00eda siendo el disco. No es una mala canci\u00f3n y en cualquier otro disco gen\u00e9rico de <em>thrash<\/em>\u00a0ser\u00eda incluso un sencillo exitoso, pero como track intermedio se espera algo m\u00e1s y sin embargo suena a una canci\u00f3n que cualquier <em>thrashero<\/em> de cochera podr\u00eda tener en sus composiciones. Todo lo contrario a <em>&#8220;Prince of Saiyans&#8221;\u00a0<\/em>cuya composici\u00f3n suena a una de las m\u00e1s elaboradas y bien trabajadas de todo el disco sin importar no sea ni muy r\u00e1pida o muy pegajosa: <strong>Vegeta<\/strong> estamos seguros estar\u00eda orgulloso del tema que le dedicaron.\u00a0<i>\u00a0&#8220;Leave your god behind&#8221;\u00a0<\/i>suena a una extra\u00f1a mezcla de metalcore acelerado, donde las guitarras de<em>\u00a0Marc Busqu\u00e9\u00a0y\u00a0Albert Requena\u00a0<\/em>se llevan el tema con sus incisivos solos. Y llegamos a <em>&#8220;Cut the Shit&#8221;\u00a0<\/em>que es un tema rasposo y violento,\u00a0 que te inspira a querer romperle la nariz a alguien que te haya hecho pasar un mal rato. Para cerrar con broche de oro, el disco cierra con <em>&#8220;The North Remembers&#8221; ,\u00a0<\/em>un tema sumamente veloz y con influencias de sonido\u00a0<i>\u00a0Gothenburg\u00a0<\/i>of bands like <strong>Dark Tranquility<\/strong> or <strong>At the Gates<\/strong>, pero que nunca deja de sonar a <em>thrash<\/em> que es sin duda lo que mejor saben hacer estos chicos.\u00a0 Todo con una letra inspirada en la famosa serie <strong>Juego de Tronos.\u00a0<\/strong><\/p>\n<p>En conclusi\u00f3n\u00a0<strong>&#8220;Against the Odds&#8221;<\/strong>\u00a0es una excelente pieza de <em>thrash<\/em> que le sigue dando vida al g\u00e9nero\u00a0 a trav\u00e9s de sangre nueva, con una selecci\u00f3n de melod\u00edas que jam\u00e1s te aburre por ser todas tan distintas pero a la vez\u00a0 de tan de buena base compartida entre si. Cuando uno adquiere un disco de <em>thrash\u00a0<\/em>reza porque el \u00e1lbum no sea una linea mon\u00f3tona canci\u00f3n tras canci\u00f3n, y que no parezca un refrito de los \u00e9xitos de las viejas glorias del g\u00e9nero. <strong>Crisix<\/strong> en ese rubro se anota una enorme paloma por entregarnos un material que te mantendr\u00e1 entretenido y con las pulsaciones a tope de principio a fin.<\/p>\n<p>&nbsp;<\/p>\n<div class=\"lets-review-block__wrap lets-review-block__wrap-10 lr-cf lets-review-wrap-21834 lets-review--center lets-review-skin-1 lets-review-design-3 lets-review-ani-1 lets-review-score-type-1 lets-review-type-2 lets-review-score-type__bar proscons__off\" data-design=\"3\" data-score-type=\"1\" data-skin=\"1\"><div class=\"lets-review-block lets-review-block__bg\"><\/div><div class=\"lets-review-block lets-review-block__main-title lr-vc lets-review-block__pad\"><\/div><div class=\"lets-review-block lets-review-block__conclusion__wrap lets-review-block__pad\"><div class=\"lets-review-block__conclusion__title lets-review-block__title lr-font-h\" style=\"\">Un disco de thrash veloz y versatil que te volar\u00e1 la cabeza <\/div><div class=\"lets-review-block__conclusion\">Crisix demuestra el porqu\u00e9 es una de las bandas de m\u00e1s proyecci\u00f3n a nivel mundial en la escena del thrash, con un disco brutal y que no da respiro ; alejandose magistralmente de lo de siempre dentro del g\u00e9nero. <\/div><\/div><div class=\"lets-review-block lets-review-block__final-score lets-review-block__final-score-type-1 lets-review-block__pad score-level-1\"><div class=\"score__wrap lr-all-c\" style=\"border-color:#ac9449; color: #fff\"><div class=\"score\">9<\/div><\/div><\/div><\/div><script type=\"application\/ld+json\">{\"@context\": \"http:\/\/schema.org\/\",\n\t\t\t\"@type\": \"Organization\",\n\t\t\t\"name\": \"Crisix &#8211; Against the Odds\",\"review\": {\n\t\t\t\t\"@type\": \"Review\",\n\t\t\t\t\"reviewRating\": {\n\t\t\t\t\t\"@type\": \"Rating\",\n\t\t\t\t\t\"worstRating\": \"0\",\n\t\t\t\t\t\"ratingValue\": \"9.5\",\n\t\t\t\t\t\"bestRating\": \"100\"\n\t\t\t\t},\n\t\t\t\t\"author\": {\n\t\t\t\t\t\"@type\": \"Person\",\n\t\t\t\t\t\"name\": \"Jorge Figueroa Tapia\"\n\t\t\t\t}\n\t\t\t}}<\/script>","protected":false},"excerpt":{"rendered":"<p>9Crisix es una de las bandas que m\u00e1s fuerte ha pegado en la nueva ola del thrash, con un estilo fuerte y agresivo que ha dejado boquiabierta a la prensa especializada y les ha ganado un gran acumulo de elogios y por supuesto muchos fans. Los originarios de Barcelona han tenido una historia de ensue\u00f1o ganando torneo tras torneo donde se presentan, incluyendo la prestigiosa batalla del Wacken en 2009. Con 3 discos previos que solo han ido superando uno [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":21838,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[225,620],"tags":[],"class_list":["post-21834","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-album-reviews","category-thrash-metal"],"_links":{"self":[{"href":"https:\/\/summainferno.com\/en\/wp-json\/wp\/v2\/posts\/21834","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/summainferno.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/summainferno.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/summainferno.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/summainferno.com\/en\/wp-json\/wp\/v2\/comments?post=21834"}],"version-history":[{"count":0,"href":"https:\/\/summainferno.com\/en\/wp-json\/wp\/v2\/posts\/21834\/revisions"}],"wp:attachment":[{"href":"https:\/\/summainferno.com\/en\/wp-json\/wp\/v2\/media?parent=21834"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/summainferno.com\/en\/wp-json\/wp\/v2\/categories?post=21834"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/summainferno.com\/en\/wp-json\/wp\/v2\/tags?post=21834"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}