{"id":21092,"date":"2018-10-17T22:49:21","date_gmt":"2018-10-18T03:49:21","guid":{"rendered":"http:\/\/summainferno.com\/?p=21092"},"modified":"2018-10-17T22:49:21","modified_gmt":"2018-10-18T03:49:21","slug":"deshojando-el-trebol-con-flogging-molly-por-primera-vez","status":"publish","type":"post","link":"https:\/\/summainferno.com\/en\/deshojando-el-trebol-con-flogging-molly-por-primera-vez\/","title":{"rendered":"Deshojando el tr\u00e9bol con Flogging Molly por primera vez."},"content":{"rendered":"<div class=\"lets-review-block__wrap lets-review-block__wrap-10 lr-cf lets-review-wrap-21092 lets-review--left lets-review-skin-1 lets-review-design-3 lets-review-ani-1 lets-review-score-type-1 lets-review-type-1 lets-review-score-type__bar lets-review--side conclusion__off proscons__off\" data-design=\"3\" data-score-type=\"1\" data-skin=\"1\"><div class=\"lets-review-block lets-review-block__bg\"><\/div><div class=\"lets-review-block lets-review-block__final-score lets-review-block__final-score-type-1 lets-review-block__pad score-level-10\"><div class=\"score__wrap lr-all-c\" style=\"border-color:#ac9449; color: #fff\"><div class=\"score\">100<\/div><\/div><\/div><\/div><p>Al puro estilo irland\u00e9s, se vivi\u00f3 una enorme fiesta en el debut en M\u00e9xico de la banda estadounidense\u2014pero de ra\u00edces del pa\u00eds del tr\u00e9bol\u2014 <strong>Flogging Molly. <\/strong>Y no era para menos, ya que la expectativa por ver a uno de los representantes m\u00e1s conocidos del <em>celtic punk <\/em>finalmente era enorme, por lo que el Lunario del Auditorio Nacional luci\u00f3 una gran entrada de fans deseosos de vivir esta gran experiencia por primera vez.<\/p>\n<p>A las ocho en punto presenciamos primero el acto de <strong>Jos\u00e9 Meyer y los Bravos de Occidente. <\/strong>Una propuesta de <em>pop-rock<\/em> con ocho integrantes armados hasta con violines y trompetas que parec\u00eda un poco fuera de contexto por el tipo de banda estelar. No obstante a ello, la gente los recibi\u00f3 con agrado y aplausos de principio a fin, e incluso se pod\u00eda escuchar preguntas interesadas en saber quienes eran. Los tapat\u00edos se dijeron muy honrados con tocar por primera vez en este recinto y tras unos cuantos temas se fueron entre palmas para dar paso al acto principal.<\/p>\n<p><img decoding=\"async\" loading=\"lazy\" class=\"aligncenter size-full wp-image-21159\" src=\"http:\/\/summainferno.com\/wp-content\/uploads\/2018\/10\/FB_IMG_1539818130378.jpg\" alt=\"\" width=\"720\" height=\"480\" title=\"\"><noscript><img decoding=\"async\" class=\"aligncenter size-full wp-image-21159\" src=\"http:\/\/summainferno.com\/wp-content\/uploads\/2018\/10\/FB_IMG_1539818130378.jpg\" alt=\"\" width=\"720\" height=\"480\" title=\"\"><\/noscript><\/p>\n<p>El enorme tr\u00e9bol impreso en la manta trasera del escenario se ilumina con luces que recrean primero los colores de la bandera de Irlanda, para luego quitar el naranja e introducir el rojo para honrar a la de nuestro pa\u00eds. <strong>Flogging Molly<\/strong> sale al escenario al ritmo de la grabaci\u00f3n de <em>\u201cThere&#8217;s Nothing Left Pt. 1\u201d,<\/em> <em>intro<\/em> que abre su m\u00e1s reciente placa <em>\u201cLife Is Good\u201d<\/em>, para de inmediato dinamitar la tarima con <em>\u201c(No More) Paddy&#8217;s Lament\u201d<\/em> y seguir deleitando a su gente con la historia de un famoso boxeador irland\u00e9s retratada en el tema <em>\u201cThe Hand of John L. Sullivan\u201d<\/em><\/p>\n<p><img decoding=\"async\" loading=\"lazy\" class=\"aligncenter size-full wp-image-21160\" src=\"http:\/\/summainferno.com\/wp-content\/uploads\/2018\/10\/FB_IMG_1539818075265.jpg\" alt=\"\" width=\"720\" height=\"1080\" title=\"\"><noscript><img decoding=\"async\" class=\"aligncenter size-full wp-image-21160\" src=\"http:\/\/summainferno.com\/wp-content\/uploads\/2018\/10\/FB_IMG_1539818075265.jpg\" alt=\"\" width=\"720\" height=\"1080\" title=\"\"><\/noscript>Si bien es cierto el \u00e1nimo y la euforia ya estaban presentes desde el inicio, no es sino hasta <em>\u201cDrunken Lullabies<\/em>\u201d que el <em>slam<\/em> y los brincos se desatan; y como si estuvi\u00e9semos en una batalla campal desatada en alg\u00fan pub irland\u00e9s los brincos y golpes se esparcen por toda la pista en una verdadera fiesta de pasi\u00f3n y cerveza. <em>\u201cThe Likes Of You Again\u201d<\/em> and <em>\u201cSwagger\u201d<\/em> son las melod\u00edas siguientes, y todos aplauden a <strong>Dave King <\/strong>quien con su vestimenta formal y su baja estatura de verdad parece un veterano duende con la magia en las vocales para incitar al bacanal. <em>\u201cThe Days We&#8217;ve Yet to Meet\u201d <\/em>es anunciada como una de las canciones de su m\u00e1s reciente placa y a pesar de ello todo el mundo se sabe la letra, lo cual maravilla a <strong>Dave. <\/strong><em>\u201cRequiem for a Dying Song\u201d<\/em> and <em>\u201cLife in a Tenement Square\u201d<\/em> van completando el viaje musical mientras el viol\u00edn de <strong>Bridget Regan, <\/strong>esposa del <em>frontman<\/em> of <strong>Flogging Molly\u00a0<\/strong>y quien constantemente la halaga, llena el Lunario de maravillosos sonidos llenos de clase y poder.<\/p>\n<p><em>\u201cEsta es una canci\u00f3n que habla del positivismo, de siempre ser uno mismo y siempre obrar bien\u201d <\/em>indicates <strong>Dave King<\/strong> al micr\u00f3fono para dejarse ir con <em>\u201cFloat\u201d,<\/em> haciendo la se\u00f1al de la paz e incluso un coraz\u00f3n con los dedos que si le sale: nuestro a\u00fan presidente deber\u00eda pedirle un par de lecciones sobre como ejecutarlo. La verdad es que <strong>Dave King<\/strong> es todo un bohemio y gusta de hablar y recordar an\u00e9cdotas entre canciones como en \u201c<em>The Spoken Wheel\/Black Friday Rule\u201d<\/em> donde habla de su padre, o bien en <em>\u201cLife Is Good\u201d<\/em> que dedica a su madre la cual seg\u00fan en propias palabras del cantante debe estar en el cielo, aunque minutos despu\u00e9s corrige y bromea diciendo probablemente est\u00e9 en un lugar m\u00e1s abajo, bebiendo y fumando.<\/p>\n<p><img decoding=\"async\" loading=\"lazy\" class=\"size-full wp-image-21161 alignleft\" src=\"http:\/\/summainferno.com\/wp-content\/uploads\/2018\/10\/FB_IMG_1539818052457.jpg\" alt=\"\" width=\"720\" height=\"1080\" title=\"\"><noscript><img decoding=\"async\" class=\"size-full wp-image-21161 alignleft\" src=\"http:\/\/summainferno.com\/wp-content\/uploads\/2018\/10\/FB_IMG_1539818052457.jpg\" alt=\"\" width=\"720\" height=\"1080\" title=\"\"><\/noscript><\/p>\n<p><em>\u201cNos tardamos mucho en venir, pero hoy concluimos una extensa gira y podemos decirles que ustedes son el mejor p\u00fablico para tocar. Tenemos que regresar el pr\u00f3ximo a\u00f1o a verles\u201d <\/em>comenta conmovido <strong>Dave King<\/strong> por la respuesta de los fans. Y es que la pista es una locura de brincos y empujones con gente que lo mismo viste playeras de metal o punk que cualquier jersey de equipos de futbol europeo; todo al ritmo de temas como \u201c<em>Devil\u00b4s Dance Floor<\/em>\u201d e <em>\u201cIf I Ever Leave This World Alive\u201d.<\/em> Arriba de la tarima la parafernalia es la misma, ya que todos los m\u00fasicos usan boinas, tirantes y sombreros muy caracter\u00edsticos de la cultura irlandesa, lo cual le da un toque por dem\u00e1s pintoresco al <em>performance<\/em>. El contraste entre la melodiosa \u201c<em>What&#8217;s Left of the Flag\u201d <\/em>seguido de la brutalidad con la que se arma el <em>moshpit<\/em> con la imparable agresividad de \u201c<em>Seven Deadly Sins\u201d, <\/em>es el marco perfecto para que <strong>Flogging Molly<\/strong> se despida por un instante de su gente.<\/p>\n<p>Abajo la gente luce incluso sombreros verdes de bomb\u00edn, cual fiesta de San Patricio en pleno octubre, y entre aplausos <strong>Flogging Molly<\/strong> regresa para interpretar <em>\u201cCrushed (Hostile Nations)\u201d<\/em>\u00a0, un tema por dem\u00e1s inspirador en el que la banda pide a la gente bailar brincando de arriba abajo; alter\u00e1ndolo con fragmentos de grandes odas como <em>\u201cWe Will Rock You\u201d<\/em> of <strong>What in <\/strong>or <em>\u201cRespect\u201d<\/em> de la reci\u00e9n finada <strong>Aretha Franklin<\/strong>. El arco\u00edris irland\u00e9s que nos ha guiado hasta aqu\u00ed llega a su fin, y la olla de oro prometida se nos es entregada en forma de la poderosa canci\u00f3n <em>\u201cSalty Dog\u201d:<\/em> tema por dem\u00e1s esperado y en el que todos los sonidos de acorde\u00f3n, cuerdas, percusiones e instrumentos de viento hacen una fusi\u00f3n apote\u00f3sica en un verdadero degenere auditivo con el que la presentaci\u00f3n llega a su final.<\/p>\n<p><img decoding=\"async\" loading=\"lazy\" class=\"aligncenter size-full wp-image-21162\" src=\"http:\/\/summainferno.com\/wp-content\/uploads\/2018\/10\/FB_IMG_1539818420976.jpg\" alt=\"\" width=\"720\" height=\"480\" title=\"\"><noscript><img decoding=\"async\" class=\"aligncenter size-full wp-image-21162\" src=\"http:\/\/summainferno.com\/wp-content\/uploads\/2018\/10\/FB_IMG_1539818420976.jpg\" alt=\"\" width=\"720\" height=\"480\" title=\"\"><\/noscript><\/p>\n<p><em>&quot;<\/em><\/p>\n<p><strong>Flogging Molly<\/strong> se despide feliz ya\u00a0con <strong>Dave<\/strong> hecho una facha sin playera y con una bandera de M\u00e9xico atada a la espalda, mientras una grabaci\u00f3n de <em>\u201cAlways Look on the Bright Side of Life\u201d <\/em>original from <strong>Monty Python <\/strong>con su inconfundible silbidito sirve de marco para la despedida. Todav\u00eda un par de m\u00fasicos deciden aventarse al p\u00fablico que los recibe como dioses, y de hecho los fans se arremolinan a su alrededor para obtener la preciada firma o foto de tal manera, que de plano la seguridad tiene que desalojar a la gente porque si por ellos y los norteamericanos fueran se quedaban toda la noche a convivir. Una verdadera fiesta donde p\u00fablico y banda pueden presumir que el tr\u00e9bol de cuatro hojas de la m\u00fasica estuvo de su lado, por la suerte de haber vivido ese mar de euforia que solo las primeras visitas traen volvi\u00e9ndolas inolvidables.<\/p>\n<div class=\"lets-review-block__wrap lets-review-block__wrap-10 lr-cf lets-review-wrap-21092 lets-review--center lets-review-skin-1 lets-review-design-3 lets-review-ani-1 lets-review-score-type-1 lets-review-type-1 lets-review-score-type__bar proscons__off\" data-design=\"3\" data-score-type=\"1\" data-skin=\"1\"><div class=\"lets-review-block lets-review-block__bg\"><\/div><div class=\"lets-review-block lets-review-block__main-title lr-vc lets-review-block__pad\"><\/div><div class=\"lets-review-block lets-review-block__conclusion__wrap lets-review-block__pad\"><div class=\"lets-review-block__conclusion__title lets-review-block__title lr-font-h\" style=\"\">\u00a1Una verdadera farra de punk celta y cerveza que nadie olvidar\u00e1!<\/div><div class=\"lets-review-block__conclusion\">Flogging Molly en su primera vez en M\u00e9xico puso a brincar como duendes a todos sus fans, en una noche m\u00e1gica tanto para los m\u00fasicos como para todos los asistentes.<\/div><\/div><div class=\"lets-review-block lets-review-block__final-score lets-review-block__final-score-type-1 lets-review-block__pad score-level-10\"><div class=\"score__wrap lr-all-c\" style=\"border-color:#ac9449; color: #fff\"><div class=\"score\">100<\/div><\/div><\/div><\/div><script type=\"application\/ld+json\">{\"@context\": \"http:\/\/schema.org\/\",\n\t\t\t\"@type\": \"Organization\",\n\t\t\t\"name\": \"Deshojando el tr\u00e9bol con Flogging Molly por primera vez.\",\"review\": {\n\t\t\t\t\"@type\": \"Review\",\n\t\t\t\t\"reviewRating\": {\n\t\t\t\t\t\"@type\": \"Rating\",\n\t\t\t\t\t\"worstRating\": \"0\",\n\t\t\t\t\t\"ratingValue\": \"100\",\n\t\t\t\t\t\"bestRating\": \"100\"\n\t\t\t\t},\n\t\t\t\t\"author\": {\n\t\t\t\t\t\"@type\": \"Person\",\n\t\t\t\t\t\"name\": \"Jorge Figueroa Tapia\"\n\t\t\t\t}\n\t\t\t}}<\/script>","protected":false},"excerpt":{"rendered":"<p>100Al puro estilo irland\u00e9s, se vivi\u00f3 una enorme fiesta en el debut en M\u00e9xico de la banda estadounidense\u2014pero de ra\u00edces del pa\u00eds del tr\u00e9bol\u2014 Flogging Molly. Y no era para menos, ya que la expectativa por ver a uno de los representantes m\u00e1s conocidos del celtic punk finalmente era enorme, por lo que el Lunario del Auditorio Nacional luci\u00f3 una gran entrada de fans deseosos de vivir esta gran experiencia por primera vez. A las ocho en punto presenciamos primero [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":21157,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1782,188],"tags":[2338,2339],"class_list":["post-21092","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-celtic-punk","category-show-review","tag-celtic-punk","tag-flogging-molly"],"_links":{"self":[{"href":"https:\/\/summainferno.com\/en\/wp-json\/wp\/v2\/posts\/21092","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/summainferno.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/summainferno.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/summainferno.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/summainferno.com\/en\/wp-json\/wp\/v2\/comments?post=21092"}],"version-history":[{"count":0,"href":"https:\/\/summainferno.com\/en\/wp-json\/wp\/v2\/posts\/21092\/revisions"}],"wp:attachment":[{"href":"https:\/\/summainferno.com\/en\/wp-json\/wp\/v2\/media?parent=21092"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/summainferno.com\/en\/wp-json\/wp\/v2\/categories?post=21092"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/summainferno.com\/en\/wp-json\/wp\/v2\/tags?post=21092"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}