{"id":13813,"date":"2016-07-10T20:57:48","date_gmt":"2016-07-11T01:57:48","guid":{"rendered":"http:\/\/summainferno.com\/?p=13813"},"modified":"2016-07-10T20:57:48","modified_gmt":"2016-07-11T01:57:48","slug":"dream-theater-viviendo-dentro-del-concepto","status":"publish","type":"post","link":"https:\/\/summainferno.com\/en\/dream-theater-viviendo-dentro-del-concepto\/","title":{"rendered":"DREAM THEATER: Viviendo dentro del concepto"},"content":{"rendered":"<div class=\"lets-review-block__wrap lets-review-block__wrap-10 lr-cf lets-review-wrap-13813 lets-review--center lets-review-skin-1 lets-review-design-1 lets-review-ani-1 lets-review-score-type-1 lets-review-type-1 lets-review-score-type__bar conclusion__off proscons__off\" data-design=\"1\" data-score-type=\"1\" data-skin=\"1\"><div class=\"lets-review-block lets-review-block__main-title lr-vc lets-review-block__pad\"><div class=\"lets-review-block__title lr-font-h\" style=\"\">Un viaje por lo sublime<\/div><\/div><div class=\"lets-review-block lets-review-block__crits lets-review-unseen\"><div class=\"lets-review-block__crit\" data-score=\"95\" data-crit=\"0\"><div class=\"lets-review-block__crit__title lr-font-h\" style=\"\">AUDIO<\/div><div class=\"lets-review-block__crit__score\">95<\/div><div class=\"score-overlay-wrap score-overlay-wrap__bar\"><div class=\"score-overlay\" style=\"width:95%;background:#ac9449;\"><\/div><\/div><\/div><div class=\"lets-review-block__crit\" data-score=\"100\" data-crit=\"1\"><div class=\"lets-review-block__crit__title lr-font-h\" style=\"\">LOCACI\u00d3N<\/div><div class=\"lets-review-block__crit__score\">100<\/div><div class=\"score-overlay-wrap score-overlay-wrap__bar\"><div class=\"score-overlay\" style=\"width:100%;background:#ac9449;\"><\/div><\/div><\/div><div class=\"lets-review-block__crit\" data-score=\"100\" data-crit=\"2\"><div class=\"lets-review-block__crit__title lr-font-h\" style=\"\">PRODUCCI\u00d3N<\/div><div class=\"lets-review-block__crit__score\">100<\/div><div class=\"score-overlay-wrap score-overlay-wrap__bar\"><div class=\"score-overlay\" style=\"width:100%;background:#ac9449;\"><\/div><\/div><\/div><div class=\"lets-review-block__user_rating with__uid\" data-uid=\"13813\" data-is-pid=\"true\"><div class=\"lets-review-block__crit lr-tip lr-user__rating\" data-title=\"Your Rating\" data-width-dir=\"l\" data-score-a=\"87\" data-score-b=\"8.7\" data-score-c=\"4.4\"><div class=\"lets-review-block__crit__title lr-font-h\" style=\"\">Readers Note<span class=\"vote__count\">14 Votes<\/span><\/div><div class=\"lets-review-block__crit__score\">87<\/div><div class=\"score-overlay-wrap score-overlay-wrap__bar\"><div class=\"score-overlay\" style=\"width:87%;background:#ac9449;\"><\/div><\/div><\/div><\/div><\/div><div class=\"lets-review-block lets-review-block__final-score lets-review-block__final-score-type-1 lets-review-block__pad score-level-9\"><div class=\"score__wrap lr-all-c\" style=\"background:#ac9449; color: #fff\"><div class=\"score\">98<\/div><\/div><\/div><\/div><script type=\"application\/ld+json\">{\"@context\": \"http:\/\/schema.org\/\",\n\t\t\t\"@type\": \"Organization\",\n\t\t\t\"name\": \"Un viaje por lo sublime\",\"review\": {\n\t\t\t\t\"@type\": \"Review\",\n\t\t\t\t\"reviewRating\": {\n\t\t\t\t\t\"@type\": \"Rating\",\n\t\t\t\t\t\"worstRating\": \"0\",\n\t\t\t\t\t\"ratingValue\": \"98\",\n\t\t\t\t\t\"bestRating\": \"100\"\n\t\t\t\t},\n\t\t\t\t\"author\": {\n\t\t\t\t\t\"@type\": \"Person\",\n\t\t\t\t\t\"name\": \"Jorge Figueroa Tapia\"\n\t\t\t\t}\n\t\t\t},\"aggregateRating\": {\n\t\t\t\t\t\"@type\": \"AggregateRating\",\n\t\t\t\t\t\"ratingValue\": \"87\",\n\t\t\t\t\t\"worstRating\": \"0\",\n\t\t\t\t\t\"bestRating\": \"100\",\n\t\t\t\t\t\"ratingCount\": \"14\"\n\t\t\t\t}}<\/script><p>El crear un disco conceptual que narre una historia de principio a fin es un riesgo que pocas bandas toman. Si a esto le sumamos la decisi\u00f3n de hacer una gira para tocarlo \u00edntegramente en vivo sin ning\u00fan otro \u00e9xito presente en el setlist, el riesgo es a\u00fan mayor. Y si para acabar lo tocan con una producci\u00f3n visual de pantallas gigantes que va narrando la historia con el grupo tocando en vivo como un soundtrack viviente, lo que nos queda es <strong>Dream Theater<\/strong> y su gira actual promoviendo su decimotercer \u00e1lbum, <em>\u201cThe Astonishing\u201d<\/em>.<\/p>\n<p>Un Pepsi Center repleto de butacas recibi\u00f3 a los fans de la banda, quienes desde un inicio fueron advertidos de que por petici\u00f3n del grupo estaba prohibido tomar fotograf\u00edas o video con cualquier tipo de dispositivo, no importando si era la c\u00e1mara Nikon m\u00e1s avanzada o el celular con la calidad m\u00e1s aborrecible. Los miembros del grupo de seguridad se tomaron muy en serio la orden y como centinelas corren a hacer que el osado que se atrevi\u00f3 a sacar su dispositivo y fue descubierto, lo guarde de inmediato. La banda quiere que la gente se sumerja completamente en el show que est\u00e1n a punto de presenciar, pero tristemente parecen estar m\u00e1s enojados porque no tendr\u00e1n un video p\u00e9simo que presumir.<\/p>\n<p>En punto de las 9 de la noche, el escenario apaga sus luces y los pendones rojos con el logotipo de la banda desaparecen. Las pantallas encienden y de inmediato los <strong>NOMACS<\/strong>, unos siniestros robots esf\u00e9ricos protagonistas del cuento se dejan ver. Es as\u00ed como comienza el m\u00e1gico show audiovisual de <em><strong>The Astonishing<\/strong><\/em>, donde con el pr\u00f3logo de <em>\u201cDystopian Overture\u201d<\/em> seguido del inicio en s\u00ed de la novela con <em>\u201cThe Gift Of Music\u201d<\/em>, la banda nos lleva de la mano por una experiencia audiovisual \u00fanica. Una obra de teatro digital con un soundtrack en directo que a trav\u00e9s de las 34 canciones tocadas, divididas en 2 actos y un encore nos hace vivir la historia de Gabriel, el \u00fanico individuo con la magia para derrocar al terrible imperio del emperador Nafaryus quien con la ayuda de los mencionados robots, ha creado un mundo desolador y gris.<\/p>\n<p>Las canciones son el acompa\u00f1amiento perfecto en cada escena, con temas melodiosos y sublimes como <em>\u201cRavenskill\u201d<\/em> donde Faythe, hija del malvado emperador crea un lazo con Gabriel a escondidas, o temas estruendosos y potentes como el que musicaliza el asesinato de Arhys (dirigente de los rebeldes y hermano de Gabriel) a manos del pr\u00edncipe Daryus, hermano de Faythe. <strong>Es de verdad como estar en una \u00f3pera futurista<\/strong>. Lo mejor es haber entendido el cuento desde el principio y dejar que las potentes cuerdas de <strong>John Petrucci<\/strong> and <strong>John Myung<\/strong> establezcan la atmosfera necesaria para que la voz de<strong> James Labrie<\/strong> haga de juglar cont\u00e1ndonos cada momento del mito. Me arrepiento de no llevar el relato impreso y seguirlo tema a tema como si de un futurista audio libro se tratara.<\/p>\n<p>Un show de casi 3 horas de duraci\u00f3n, \u00fanico en su clase, con la banda dando todo de s\u00ed para crear una experiencia inolvidable deja a todos los asistentes contentos. <strong>Jordan Ruddes<\/strong> parece un piloto m\u00e1s en una extra\u00f1a nave con su aparatoso y futurista teclado que se inclina a un lado y a otro, y aunque los fans ac\u00e9rrimos defienden que sin <strong>Mike Portnoy<\/strong> en las baquetas <strong>Dream Theater<\/strong> ya no es igual, lo cierto es que la ejecuci\u00f3n en la impresionante y descomunal bater\u00eda a cargo de<strong> Mike Mangini<\/strong> no demerita en lo m\u00e1s m\u00ednimo.<\/p>\n<p>&nbsp;<\/p>\n<p><img decoding=\"async\" loading=\"lazy\" class=\"aligncenter size-full wp-image-13815\" src=\"http:\/\/summainferno.com\/wp-content\/uploads\/2016\/07\/theaterdmex.jpg\" alt=\"theaterdmex\" width=\"960\" height=\"540\" title=\"\"><noscript><img decoding=\"async\" class=\"aligncenter size-full wp-image-13815\" src=\"http:\/\/summainferno.com\/wp-content\/uploads\/2016\/07\/theaterdmex.jpg\" alt=\"theaterdmex\" width=\"960\" height=\"540\" title=\"\"><\/noscript><\/p>\n<p>Momentos clave de la narraci\u00f3n como el encuentro de Gabriel y el emperador en un teatro abandonado descrito en <em>\u201cThe Road To Revolution\u201d<\/em>\u00a0 que de hecho da por terminado el primer acto, el asesinato por error de la princesa Faythe a manos de su hermano en <em>\u201cThe Walking Shadow\u201d<\/em> y sobretodo el momento en el que <strong>James Labrie<\/strong> pide a los asistentes ponerse todos de pie y levantar las manos y cantar como lo hace la gente del pueblo en la novela para alentar a Gabriel y que recupere su poder en <em>\u201cHymn Of A Thousand Voices<\/em>&#8221; son picos altos y sublimes del show, el cual termina con <em>\u201cAstonishing\u201d<\/em> que narra el descenlace feliz de la historia donde el emperador se redime e integra un nuevo orden que da esperanza al mundo futuro, libre de los NOMACS para siempre.<\/p>\n<p>Las luces se encienden y de s\u00fabito regresas a la realidad. Ya no est\u00e1s en el poblado de Ravenskill ni en el gran Imperio del Norte, sino que has regresado de la fantas\u00eda y estas de nuevo en el Pepsi Center. La banda se va vitoreada y aplaudida por todos y<strong> Dream Theater<\/strong> nos ha regalado haciendo gala de su nombre, una noche de teatro de sue\u00f1os y aventuras de ficci\u00f3n sencillamente inolvidable. \u00bfY las canciones cl\u00e1sicas de la banda? Ya habr\u00e1 otra oportunidad de escucharlos en vivo pues seguramente la pr\u00f3xima gira el tel\u00f3n de los gigantes del progresivo se abrir\u00e1 de nuevo para nuestro pa\u00eds.<\/p>","protected":false},"excerpt":{"rendered":"<p>Un viaje por lo sublimeAUDIO95LOCACI\u00d3N100PRODUCCI\u00d3N100Nota de lectores14 Votes8798El crear un disco conceptual que narre una historia de principio a fin es un riesgo que pocas bandas toman. Si a esto le sumamos la decisi\u00f3n de hacer una gira para tocarlo \u00edntegramente en vivo sin ning\u00fan otro \u00e9xito presente en el setlist, el riesgo es a\u00fan mayor. Y si para acabar lo tocan con una producci\u00f3n visual de pantallas gigantes que va narrando la historia con el grupo tocando en vivo [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":13817,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1809,188],"tags":[515,25,2088],"class_list":["post-13813","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-metal-conciertos-resenas","category-show-review","tag-dream-theater","tag-mexico","tag-pepsi-center-wtc"],"_links":{"self":[{"href":"https:\/\/summainferno.com\/en\/wp-json\/wp\/v2\/posts\/13813","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/summainferno.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/summainferno.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/summainferno.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/summainferno.com\/en\/wp-json\/wp\/v2\/comments?post=13813"}],"version-history":[{"count":0,"href":"https:\/\/summainferno.com\/en\/wp-json\/wp\/v2\/posts\/13813\/revisions"}],"wp:attachment":[{"href":"https:\/\/summainferno.com\/en\/wp-json\/wp\/v2\/media?parent=13813"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/summainferno.com\/en\/wp-json\/wp\/v2\/categories?post=13813"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/summainferno.com\/en\/wp-json\/wp\/v2\/tags?post=13813"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}